{"id":30308,"date":"2022-11-16T09:43:58","date_gmt":"2022-11-16T07:43:58","guid":{"rendered":"https:\/\/europeanvalues.cz\/?p=30308"},"modified":"2022-12-14T08:57:17","modified_gmt":"2022-12-14T06:57:17","slug":"tagesspiegel","status":"publish","type":"post","link":"https:\/\/europeanvalues.cz\/en\/tagesspiegel\/","title":{"rendered":"Tagesspiegel"},"content":{"rendered":"<p><a href=\"https:\/\/www.tagesspiegel.de\/politik\/hochrangige-besuche-in-taipeh-und-berlin-andert-die-bundesregierung-ihre-taiwan-politik-8880115.html\" target=\"_blank\" rel=\"noopener\">Hochrangige Besuche in Taipeh und Berlin: \u00c4ndert die Bundesregierung ihre Taiwan-Politik?<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hochrangige Besuche in Taipeh und Berlin: \u00c4ndert die Bundesregierung ihre Taiwan-Politik?<\/p>\n","protected":false},"author":7,"featured_media":15647,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[135],"tags":[495],"class_list":["post-30308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-my-v-mediich","tag-marcin-jerzewski"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tagesspiegel - European Values Center for Security Policy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europeanvalues.cz\/en\/tagesspiegel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tagesspiegel - European Values Center for Security Policy\" \/>\n<meta property=\"og:description\" content=\"Hochrangige Besuche in Taipeh und Berlin: \u00c4ndert die Bundesregierung ihre Taiwan-Politik?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europeanvalues.cz\/en\/tagesspiegel\/\" \/>\n<meta property=\"og:site_name\" content=\"European Values Center for Security Policy\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-16T07:43:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-14T06:57:17+00:00\" \/>\n<meta name=\"author\" content=\"Ond\u0159ej Ber\u00e1nek\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ond\u0159ej Ber\u00e1nek\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/tagesspiegel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/tagesspiegel\\\/\"},\"author\":{\"name\":\"Ond\u0159ej Ber\u00e1nek\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#\\\/schema\\\/person\\\/7724fb271acacd215231c937a200a510\"},\"headline\":\"Tagesspiegel\",\"datePublished\":\"2022-11-16T07:43:58+00:00\",\"dateModified\":\"2022-12-14T06:57:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/tagesspiegel\\\/\"},\"wordCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/tagesspiegel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/europeanvalues.cz\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/pexels-felix-mittermeier-1269805-scaled.jpg\",\"keywords\":[\"Marcin Jerzewski\"],\"articleSection\":[\"My v m\u00e9di\u00edch\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/tagesspiegel\\\/\",\"url\":\"https:\\\/\\\/europeanvalues.cz\\\/tagesspiegel\\\/\",\"name\":\"Tagesspiegel - European Values Center for Security Policy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/tagesspiegel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/tagesspiegel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/europeanvalues.cz\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/pexels-felix-mittermeier-1269805-scaled.jpg\",\"datePublished\":\"2022-11-16T07:43:58+00:00\",\"dateModified\":\"2022-12-14T06:57:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/tagesspiegel\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/europeanvalues.cz\\\/tagesspiegel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/tagesspiegel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/europeanvalues.cz\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/pexels-felix-mittermeier-1269805-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/europeanvalues.cz\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/pexels-felix-mittermeier-1269805-scaled.jpg\",\"width\":2560,\"height\":1047},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/tagesspiegel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tagesspiegel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/\",\"name\":\"European Values Center for Security Policy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#organization\",\"name\":\"European Values Center for Security Policy\",\"url\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/europeanvalues.cz\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-horse.svg\",\"contentUrl\":\"https:\\\/\\\/europeanvalues.cz\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-horse.svg\",\"caption\":\"European Values Center for Security Policy\"},\"image\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#\\\/schema\\\/person\\\/7724fb271acacd215231c937a200a510\",\"name\":\"Ond\u0159ej Ber\u00e1nek\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f89146eedd3ddff4c25476fbcda302860efe5ac77dc8e7ad9cd2b43a88c341ce?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f89146eedd3ddff4c25476fbcda302860efe5ac77dc8e7ad9cd2b43a88c341ce?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f89146eedd3ddff4c25476fbcda302860efe5ac77dc8e7ad9cd2b43a88c341ce?s=96&r=g\",\"caption\":\"Ond\u0159ej Ber\u00e1nek\"},\"url\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/author\\\/ond-ber\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tagesspiegel - European Values Center for Security Policy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europeanvalues.cz\/en\/tagesspiegel\/","og_locale":"en_US","og_type":"article","og_title":"Tagesspiegel - European Values Center for Security Policy","og_description":"Hochrangige Besuche in Taipeh und Berlin: \u00c4ndert die Bundesregierung ihre Taiwan-Politik?","og_url":"https:\/\/europeanvalues.cz\/en\/tagesspiegel\/","og_site_name":"European Values Center for Security Policy","article_published_time":"2022-11-16T07:43:58+00:00","article_modified_time":"2022-12-14T06:57:17+00:00","author":"Ond\u0159ej Ber\u00e1nek","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ond\u0159ej Ber\u00e1nek","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/europeanvalues.cz\/tagesspiegel\/#article","isPartOf":{"@id":"https:\/\/europeanvalues.cz\/tagesspiegel\/"},"author":{"name":"Ond\u0159ej Ber\u00e1nek","@id":"https:\/\/europeanvalues.cz\/en\/#\/schema\/person\/7724fb271acacd215231c937a200a510"},"headline":"Tagesspiegel","datePublished":"2022-11-16T07:43:58+00:00","dateModified":"2022-12-14T06:57:17+00:00","mainEntityOfPage":{"@id":"https:\/\/europeanvalues.cz\/tagesspiegel\/"},"wordCount":12,"publisher":{"@id":"https:\/\/europeanvalues.cz\/en\/#organization"},"image":{"@id":"https:\/\/europeanvalues.cz\/tagesspiegel\/#primaryimage"},"thumbnailUrl":"https:\/\/europeanvalues.cz\/wp-content\/uploads\/2021\/08\/pexels-felix-mittermeier-1269805-scaled.jpg","keywords":["Marcin Jerzewski"],"articleSection":["My v m\u00e9di\u00edch"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/europeanvalues.cz\/tagesspiegel\/","url":"https:\/\/europeanvalues.cz\/tagesspiegel\/","name":"Tagesspiegel - European Values Center for Security Policy","isPartOf":{"@id":"https:\/\/europeanvalues.cz\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europeanvalues.cz\/tagesspiegel\/#primaryimage"},"image":{"@id":"https:\/\/europeanvalues.cz\/tagesspiegel\/#primaryimage"},"thumbnailUrl":"https:\/\/europeanvalues.cz\/wp-content\/uploads\/2021\/08\/pexels-felix-mittermeier-1269805-scaled.jpg","datePublished":"2022-11-16T07:43:58+00:00","dateModified":"2022-12-14T06:57:17+00:00","breadcrumb":{"@id":"https:\/\/europeanvalues.cz\/tagesspiegel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europeanvalues.cz\/tagesspiegel\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europeanvalues.cz\/tagesspiegel\/#primaryimage","url":"https:\/\/europeanvalues.cz\/wp-content\/uploads\/2021\/08\/pexels-felix-mittermeier-1269805-scaled.jpg","contentUrl":"https:\/\/europeanvalues.cz\/wp-content\/uploads\/2021\/08\/pexels-felix-mittermeier-1269805-scaled.jpg","width":2560,"height":1047},{"@type":"BreadcrumbList","@id":"https:\/\/europeanvalues.cz\/tagesspiegel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/europeanvalues.cz\/en\/"},{"@type":"ListItem","position":2,"name":"Tagesspiegel"}]},{"@type":"WebSite","@id":"https:\/\/europeanvalues.cz\/en\/#website","url":"https:\/\/europeanvalues.cz\/en\/","name":"European Values Center for Security Policy","description":"","publisher":{"@id":"https:\/\/europeanvalues.cz\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europeanvalues.cz\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europeanvalues.cz\/en\/#organization","name":"European Values Center for Security Policy","url":"https:\/\/europeanvalues.cz\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europeanvalues.cz\/en\/#\/schema\/logo\/image\/","url":"https:\/\/europeanvalues.cz\/wp-content\/uploads\/2021\/04\/logo-horse.svg","contentUrl":"https:\/\/europeanvalues.cz\/wp-content\/uploads\/2021\/04\/logo-horse.svg","caption":"European Values Center for Security Policy"},"image":{"@id":"https:\/\/europeanvalues.cz\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/europeanvalues.cz\/en\/#\/schema\/person\/7724fb271acacd215231c937a200a510","name":"Ond\u0159ej Ber\u00e1nek","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/f89146eedd3ddff4c25476fbcda302860efe5ac77dc8e7ad9cd2b43a88c341ce?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f89146eedd3ddff4c25476fbcda302860efe5ac77dc8e7ad9cd2b43a88c341ce?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f89146eedd3ddff4c25476fbcda302860efe5ac77dc8e7ad9cd2b43a88c341ce?s=96&r=g","caption":"Ond\u0159ej Ber\u00e1nek"},"url":"https:\/\/europeanvalues.cz\/en\/author\/ond-ber\/"}]}},"_links":{"self":[{"href":"https:\/\/europeanvalues.cz\/en\/wp-json\/wp\/v2\/posts\/30308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europeanvalues.cz\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/europeanvalues.cz\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/europeanvalues.cz\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/europeanvalues.cz\/en\/wp-json\/wp\/v2\/comments?post=30308"}],"version-history":[{"count":1,"href":"https:\/\/europeanvalues.cz\/en\/wp-json\/wp\/v2\/posts\/30308\/revisions"}],"predecessor-version":[{"id":30309,"href":"https:\/\/europeanvalues.cz\/en\/wp-json\/wp\/v2\/posts\/30308\/revisions\/30309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europeanvalues.cz\/en\/wp-json\/wp\/v2\/media\/15647"}],"wp:attachment":[{"href":"https:\/\/europeanvalues.cz\/en\/wp-json\/wp\/v2\/media?parent=30308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europeanvalues.cz\/en\/wp-json\/wp\/v2\/categories?post=30308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europeanvalues.cz\/en\/wp-json\/wp\/v2\/tags?post=30308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}