{"id":34394,"date":"2023-08-08T14:51:32","date_gmt":"2023-08-08T12:51:32","guid":{"rendered":"https:\/\/europeanvalues.cz\/?p=34394"},"modified":"2024-03-11T15:32:24","modified_gmt":"2024-03-11T13:32:24","slug":"ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties","status":"publish","type":"post","link":"https:\/\/europeanvalues.cz\/cs\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/","title":{"rendered":"Na pozad\u00ed vla\u017en\u00fdch vztah\u016f mezi Pekingem a Manilou nav\u0161t\u00edvila Filip\u00edny p\u0159edsedkyn\u011b EK von der Leyen"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"34394\" class=\"elementor elementor-34394\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76528b78 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76528b78\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6257941f\" data-id=\"6257941f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-19a52c62 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19a52c62\" data-element_type=\"section\" data-e-type=\"section\" data-no-translation=\"\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-10745b01\" data-id=\"10745b01\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ae89d4f elementor-widget elementor-widget-text-editor\" data-id=\"1ae89d4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Co se d\u011bje?<\/h2><p>P\u0159edsedkyn\u011b Evropsk\u00e9 komise Ursula von der Leyen b\u011bhem sv\u00e9 n\u00e1v\u0161t\u011bvy Filip\u00edn minul\u00fd t\u00fdden ve sv\u00e9m\u00a0<a href=\"https:\/\/mailing.europeanvalues.cz\/link\/c\/YT0yMjc2NzAzMjQ5MDQ4Mjc0MDQ4JmM9cDlrMiZlPTc2MDQ0OTk0JmI9MTE4NTk5MTU3MiZkPXgzZzRiNW4=.Qs3wQnroFXoV18PmMrYr6CXiorzlRMB8Vw89jbUCbkU\" target=\"_blank\" rel=\"noopener\">hlavn\u00edm projevu<\/a> p\u0159\u00edmo\u00a0<strong>kritizovala \u010c\u00ednu za zpochyb\u0148ov\u00e1n\u00ed sv\u011btov\u00e9ho \u0159\u00e1du<\/strong>. Na Filip\u00ednsk\u00e9m podnikatelsk\u00e9m f\u00f3ru von der Leyen prohl\u00e1sila, \u017ee \u010c\u00edna \u201eje\u0161t\u011b mus\u00ed pln\u011b p\u0159evz\u00edt odpov\u011bdnost podle Charty OSN za zachov\u00e1n\u00ed suverenity a \u00fazemn\u00ed celistvosti Ukrajiny\u201c. Varovala, \u017ee \u010d\u00ednsk\u00e1 demonstrace vojensk\u00e9 s\u00edly v ji\u017en\u00edch a v\u00fdchodo\u010d\u00ednsk\u00fdch mo\u0159\u00edch a v Tchajwansk\u00e9m pr\u016flivu m\u016f\u017ee m\u00edt \u201e<strong>glob\u00e1ln\u00ed dopady<\/strong>\u201c, a z\u00e1rove\u0148 zd\u016fraznila, \u017ee EU posiluje svou anga\u017eovanost v Indo-Pacifiku. Projev je pot\u0159eba vn\u00edmat v kontextu\u00a0<strong>prohlubuj\u00edc\u00ed se propasti mezi Manilou a Pekingem <\/strong>za \u00fa\u0159aduj\u00edc\u00edho prezidenta Ferdinanda \u201eBongbonga\u201c R. Marcose mlad\u0161\u00edho.<\/p><h2>\u00a0<\/h2><h2>Jak\u00e9 jsou \u0161ir\u0161\u00ed souvislosti?<\/h2><p>Po n\u00e1stupu p\u0159edchoz\u00edho prezidenta Rodriga Duterteho k moci nastalo ve vztaz\u00edch mezi Manilou a Pekingem\u00a0<strong>obdob\u00ed l\u00edb\u00e1nek<\/strong>. Populistick\u00fd v\u016fdce se odklonil od asertivn\u00edho postoje v\u016f\u010di \u010c\u00edn\u011b sv\u00e9ho p\u0159edch\u016fdce Benigna Aquina III. a provedl reset vztah\u016f sv\u00e9 zem\u011b s \u010cLR, kter\u00fd byl zam\u011b\u0159en p\u0159edev\u0161\u00edm na zaji\u0161t\u011bn\u00ed financov\u00e1n\u00ed Duterteho vlajkov\u00e9ho programu rozvoje infrastruktury\u00a0<a href=\"https:\/\/mailing.europeanvalues.cz\/link\/c\/YT0yMjc2NzAzMjQ5MDQ4Mjc0MDQ4JmM9cDlrMiZlPTc2MDQ0OTk0JmI9MTE4NTk5MTU4MSZkPWcwcDFxNno=.FxuoVKD0iVzjehPtfBpYY2nZLVpesyHAFNTDM1PJMMI\" target=\"_blank\" rel=\"noopener\"><strong>Budujte, budujte, budujte<\/strong><\/a>\u00a0za 160 milion\u016f USD. Duterteho administrativa pova\u017eovala \u010d\u00ednskou iniciativu P\u00e1sma a stezky za atraktivn\u00ed zdroj financov\u00e1n\u00ed infrastrukturn\u00edch projekt\u016f. Nav\u00edc k prohlubov\u00e1n\u00ed vazeb s Pekingem do\u0161lo soub\u011b\u017en\u011b s\u00a0<a href=\"https:\/\/mailing.europeanvalues.cz\/link\/c\/YT0yMjc2NzAzMjQ5MDQ4Mjc0MDQ4JmM9cDlrMiZlPTc2MDQ0OTk0JmI9MTE4NTk5MTU5MCZkPXA1YTFrNXc=.08Q7GT827AUxHkowByVCkBfWarVI-cm4sZoXb_cUKJw\" target=\"_blank\" rel=\"noopener\">odklonem od USA<\/a>, co\u017e byl proces podpo\u0159en\u00fd Duterteho\u00a0<a href=\"https:\/\/mailing.europeanvalues.cz\/link\/c\/YT0yMjc2NzAzMjQ5MDQ4Mjc0MDQ4JmM9cDlrMiZlPTc2MDQ0OTk0JmI9MTE4NTk5MTU5NyZkPW8wbjhwNHE=.GQDavhWN0OqcuZ3-TZ-FHmwN0T2aXuq43GLnC8KxIbQ\" target=\"_blank\" rel=\"noopener\">protiamerick\u00fdm sentimentem<\/a>.<\/p><p>P\u0159esto \u010d\u00ednsk\u00e9 sliby o lukrativn\u00edch ekonomick\u00fdch obchodech z\u016fstaly z velk\u00e9 \u010d\u00e1sti <a href=\"https:\/\/mailing.europeanvalues.cz\/link\/c\/YT0yMjc2NzAzMjQ5MDQ4Mjc0MDQ4JmM9cDlrMiZlPTc2MDQ0OTk0JmI9MTE4NTk5MTYwNiZkPXA2aDVxMno=.OWFv5pvexXeQsTWI8jvhKcKTXcGPhqbmA0HCvn902eA\" target=\"_blank\" rel=\"noopener\">nenapln\u011bny<\/a>. \u010c\u00edna nav\u00edc pokra\u010dovala ve sv\u00e9m pron\u00e1sledov\u00e1n\u00ed filip\u00ednsk\u00e9 pob\u0159e\u017en\u00ed str\u00e1\u017ee, zejm\u00e9na v bl\u00edzkosti m\u011bl\u010diny Scarborough. Rostouc\u00ed n\u00e1mo\u0159n\u00ed nap\u011bt\u00ed tak\u00e9 vedlo k <a href=\"https:\/\/mailing.europeanvalues.cz\/link\/c\/YT0yMjc2NzAzMjQ5MDQ4Mjc0MDQ4JmM9cDlrMiZlPTc2MDQ0OTk0JmI9MTE4NTk5MTYxNSZkPXU0ejNvM2s=.Um2x9J0GAMjH_mmWNBkFCRp3XXKscS48OqkoSdwE2rQ\" target=\"_blank\" rel=\"noopener\">incidentu v oblasti m\u011bl\u010diny Reed Bank<\/a>, p\u0159i kter\u00e9m podez\u0159el\u00e1 \u010d\u00ednsk\u00e1 n\u00e1mo\u0159n\u00ed milice potopila filip\u00ednsk\u00e9 ryb\u00e1\u0159sk\u00e9 plavidlo. N\u00e1mo\u0159n\u00ed nap\u011bt\u00ed mezi \u010c\u00ednou a Filip\u00ednami eskalovalo naposledy\u00a05. srpna, kdy\u017e filip\u00ednsk\u00e1 pob\u0159e\u017en\u00ed str\u00e1\u017e obvinila \u010d\u00ednskou pob\u0159e\u017en\u00ed str\u00e1\u017e z vniknut\u00ed do jej\u00edch vod a \u00fatoku\u00a0vodn\u00edmi d\u011bly na jej\u00ed lod\u011b.\u00a0Duterte\u00a0ke konci sv\u00e9 administrativy obr\u00e1til sm\u011br zahrani\u010dn\u00ed politiky zp\u011bt k Washingtonu, v d\u016fsledku \u010deho\u017e se <a href=\"https:\/\/mailing.europeanvalues.cz\/link\/c\/YT0yMjc2NzAzMjQ5MDQ4Mjc0MDQ4JmM9cDlrMiZlPTc2MDQ0OTk0JmI9MTE4NTk5MTYyMiZkPXgzbjR2NGY=.7OMoZRzYRBCJ60HuB_tr_7_AGusuO9WRkxDdqPYN1-o\" target=\"_blank\" rel=\"noopener\">Filip\u00edny staly<\/a> <strong>nejv\u011bt\u0161\u00edm p\u0159\u00edjemcem americk\u00e9 vojensk\u00e9 pomoci v indopacifick\u00e9m regionu<\/strong>.<\/p><p>Sou\u010dasn\u00e1 Marcosova administrativa tedy do zna\u010dn\u00e9 m\u00edry pokra\u010duje v trajektorii zahrani\u010dn\u00ed politiky Filip\u00edn nastolen\u00e9 v posledn\u00edm roce Duterteho vl\u00e1dy \u2013\u00a0<strong>obnovuje pozitivn\u00ed vztahy s USA a distancuje se od \u010c\u00edny.<\/strong><\/p><h2>\u00a0<\/h2><h2>Pro\u010d je to d\u016fle\u017eit\u00e9?<\/h2><p>Evropsk\u00e1 unie se sna\u017e\u00ed t\u011b\u017eit z politick\u00e9ho obratu v Manile, proto\u017ee\u00a0<strong>pova\u017euje Filip\u00edny za d\u016fle\u017eit\u00e9ho partnera\u00a0<\/strong>v indopacifick\u00e9m regionu.<\/p><p>B\u011bhem n\u00e1v\u0161t\u011bvy von der Leyen v Manile bylo ozn\u00e1meno z\u00e1sadn\u00ed\u00a0<a href=\"https:\/\/mailing.europeanvalues.cz\/link\/c\/YT0yMjc2NzAzMjQ5MDQ4Mjc0MDQ4JmM9cDlrMiZlPTc2MDQ0OTk0JmI9MTE4NTk5MTYyOCZkPXI4ZjB0NmE=.sBDEFvyImnTvg6UDAOe89de6IJSUGdBSJYgFmaRKZhw\" target=\"_blank\" rel=\"noopener\">obnoven\u00ed<\/a>\u00a0rozhovor\u016f o bilater\u00e1ln\u00ed\u00a0<strong>dohod\u011b o voln\u00e9m obchodu<\/strong>\u00a0(FTA). Jedn\u00e1n\u00ed o voln\u00e9m obchodu mezi EU a Filip\u00ednami za\u010dala v roce 2015, v roce 2017 v\u0161ak byla za Duterteho vl\u00e1dy zastavena kv\u016fli poru\u0161ov\u00e1n\u00ed lidsk\u00fdch pr\u00e1v a jeho krvav\u00e9 protidrogov\u00e9 kampani.\u00a0<\/p><p>Obnoven\u00ed obchodn\u00edch rozhovor\u016f nazna\u010duje, \u017ee Brusel, a konkr\u00e9tn\u011b \u201egeopolitick\u00e1 komise\u201c von der Leyen, st\u00e1le v\u00edce vn\u00edm\u00e1 Filip\u00edny\u00a0<strong>jako kl\u00ed\u010dov\u00e9ho politick\u00e9ho a ekonomick\u00e9ho partnera v Indo-Pacifiku<\/strong>. Prohlouben\u00ed vazeb mezi Manilou a Washingtonem v kontextu ochlazen\u00ed vazeb s Pekingem t\u00e9to zm\u011bn\u011b pom\u00e1h\u00e1. Krom\u011b toho jsou Filip\u00edny\u00a0<strong>druh\u00fdm nejv\u011bt\u0161\u00edm sv\u011btov\u00fdm producentem niklu<\/strong>, kter\u00fd je identifikov\u00e1n jako kritick\u00e1 i strategick\u00e1 surovina, ale jeho v\u00fdvoz je m\u00e1lo diverzifikovan\u00fd, jeliko\u017e 90 procent m\u00ed\u0159\u00ed do \u010c\u00edny. P\u0159esm\u011brov\u00e1n\u00ed v\u00fdvozu by mohlo sn\u00ed\u017eit filip\u00ednskou zranitelnost a z\u00e1rove\u0148 napom\u00e1hat EU v procesu\u00a0<strong>sni\u017eov\u00e1n\u00ed rizik<\/strong>\u00a0d\u00edky\u00a0<strong>diverzifikaci dodavatelsk\u00e9ho \u0159et\u011bzce.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>What is going on? During her last week\u2019s visit to the Philippines, European Commission President Ursula von der Leyen delivered a\u00a0keynote speech\u00a0in which she directly\u00a0pummeled China for challenging the global order.\u00a0Speaking at the Philippines Business Forum, von der Leyen asserted that China \u201chas yet to assume fully its responsibility under the UN Charter to uphold [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":34395,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[500],"tags":[495],"class_list":["post-34394","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles","tag-marcin-jerzewski"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EC President von der Leyen Visits Philippines Amid Weak Beijing-Manila Ties - European Values Center for Security Policy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europeanvalues.cz\/cs\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/\" \/>\n<meta property=\"og:locale\" content=\"cs_CZ\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EC President von der Leyen Visits Philippines Amid Weak Beijing-Manila Ties - European Values Center for Security Policy\" \/>\n<meta property=\"og:description\" content=\"What is going on? During her last week\u2019s visit to the Philippines, European Commission President Ursula von der Leyen delivered a\u00a0keynote speech\u00a0in which she directly\u00a0pummeled China for challenging the global order.\u00a0Speaking at the Philippines Business Forum, von der Leyen asserted that China \u201chas yet to assume fully its responsibility under the UN Charter to uphold [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europeanvalues.cz\/cs\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/\" \/>\n<meta property=\"og:site_name\" content=\"European Values Center for Security Policy\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-08T12:51:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-11T13:32:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europeanvalues.cz\/wp-content\/uploads\/2023\/08\/Flag_of_Philippines.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2160\" \/>\n\t<meta property=\"og:image:height\" content=\"1136\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ond\u0159ej Ber\u00e1nek\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Napsal(a)\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ond\u0159ej Ber\u00e1nek\" \/>\n\t<meta name=\"twitter:label2\" content=\"Odhadovan\u00e1 doba \u010dten\u00ed\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\\\/\"},\"author\":{\"name\":\"Ond\u0159ej Ber\u00e1nek\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#\\\/schema\\\/person\\\/7724fb271acacd215231c937a200a510\"},\"headline\":\"EC President von der Leyen Visits Philippines Amid Weak Beijing-Manila Ties\",\"datePublished\":\"2023-08-08T12:51:32+00:00\",\"dateModified\":\"2024-03-11T13:32:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\\\/\"},\"wordCount\":1288,\"publisher\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/europeanvalues.cz\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Flag_of_Philippines.jpg\",\"keywords\":[\"Marcin Jerzewski\"],\"articleSection\":[\"Articles\"],\"inLanguage\":\"cs\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\\\/\",\"url\":\"https:\\\/\\\/europeanvalues.cz\\\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\\\/\",\"name\":\"EC President von der Leyen Visits Philippines Amid Weak Beijing-Manila Ties - European Values Center for Security Policy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/europeanvalues.cz\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Flag_of_Philippines.jpg\",\"datePublished\":\"2023-08-08T12:51:32+00:00\",\"dateModified\":\"2024-03-11T13:32:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\\\/#breadcrumb\"},\"inLanguage\":\"cs\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/europeanvalues.cz\\\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\\\/#primaryimage\",\"url\":\"https:\\\/\\\/europeanvalues.cz\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Flag_of_Philippines.jpg\",\"contentUrl\":\"https:\\\/\\\/europeanvalues.cz\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Flag_of_Philippines.jpg\",\"width\":2160,\"height\":1136},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dom\u016f\",\"item\":\"https:\\\/\\\/europeanvalues.cz\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EC President von der Leyen Visits Philippines Amid Weak Beijing-Manila Ties\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/\",\"name\":\"European Values Center for Security Policy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cs\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#organization\",\"name\":\"European Values Center for Security Policy\",\"url\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/europeanvalues.cz\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-horse.svg\",\"contentUrl\":\"https:\\\/\\\/europeanvalues.cz\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-horse.svg\",\"caption\":\"European Values Center for Security Policy\"},\"image\":{\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/europeanvalues.cz\\\/en\\\/#\\\/schema\\\/person\\\/7724fb271acacd215231c937a200a510\",\"name\":\"Ond\u0159ej Ber\u00e1nek\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"cs\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f89146eedd3ddff4c25476fbcda302860efe5ac77dc8e7ad9cd2b43a88c341ce?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f89146eedd3ddff4c25476fbcda302860efe5ac77dc8e7ad9cd2b43a88c341ce?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f89146eedd3ddff4c25476fbcda302860efe5ac77dc8e7ad9cd2b43a88c341ce?s=96&r=g\",\"caption\":\"Ond\u0159ej Ber\u00e1nek\"},\"url\":\"https:\\\/\\\/europeanvalues.cz\\\/cs\\\/author\\\/ond-ber\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EC President von der Leyen Visits Philippines Amid Weak Beijing-Manila Ties - European Values Center for Security Policy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europeanvalues.cz\/cs\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/","og_locale":"cs_CZ","og_type":"article","og_title":"EC President von der Leyen Visits Philippines Amid Weak Beijing-Manila Ties - European Values Center for Security Policy","og_description":"What is going on? During her last week\u2019s visit to the Philippines, European Commission President Ursula von der Leyen delivered a\u00a0keynote speech\u00a0in which she directly\u00a0pummeled China for challenging the global order.\u00a0Speaking at the Philippines Business Forum, von der Leyen asserted that China \u201chas yet to assume fully its responsibility under the UN Charter to uphold [&hellip;]","og_url":"https:\/\/europeanvalues.cz\/cs\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/","og_site_name":"European Values Center for Security Policy","article_published_time":"2023-08-08T12:51:32+00:00","article_modified_time":"2024-03-11T13:32:24+00:00","og_image":[{"width":2160,"height":1136,"url":"https:\/\/europeanvalues.cz\/wp-content\/uploads\/2023\/08\/Flag_of_Philippines.jpg","type":"image\/jpeg"}],"author":"Ond\u0159ej Ber\u00e1nek","twitter_card":"summary_large_image","twitter_misc":{"Napsal(a)":"Ond\u0159ej Ber\u00e1nek","Odhadovan\u00e1 doba \u010dten\u00ed":"5 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/europeanvalues.cz\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/#article","isPartOf":{"@id":"https:\/\/europeanvalues.cz\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/"},"author":{"name":"Ond\u0159ej Ber\u00e1nek","@id":"https:\/\/europeanvalues.cz\/en\/#\/schema\/person\/7724fb271acacd215231c937a200a510"},"headline":"EC President von der Leyen Visits Philippines Amid Weak Beijing-Manila Ties","datePublished":"2023-08-08T12:51:32+00:00","dateModified":"2024-03-11T13:32:24+00:00","mainEntityOfPage":{"@id":"https:\/\/europeanvalues.cz\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/"},"wordCount":1288,"publisher":{"@id":"https:\/\/europeanvalues.cz\/en\/#organization"},"image":{"@id":"https:\/\/europeanvalues.cz\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/#primaryimage"},"thumbnailUrl":"https:\/\/europeanvalues.cz\/wp-content\/uploads\/2023\/08\/Flag_of_Philippines.jpg","keywords":["Marcin Jerzewski"],"articleSection":["Articles"],"inLanguage":"cs"},{"@type":"WebPage","@id":"https:\/\/europeanvalues.cz\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/","url":"https:\/\/europeanvalues.cz\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/","name":"EC President von der Leyen Visits Philippines Amid Weak Beijing-Manila Ties - European Values Center for Security Policy","isPartOf":{"@id":"https:\/\/europeanvalues.cz\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/europeanvalues.cz\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/#primaryimage"},"image":{"@id":"https:\/\/europeanvalues.cz\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/#primaryimage"},"thumbnailUrl":"https:\/\/europeanvalues.cz\/wp-content\/uploads\/2023\/08\/Flag_of_Philippines.jpg","datePublished":"2023-08-08T12:51:32+00:00","dateModified":"2024-03-11T13:32:24+00:00","breadcrumb":{"@id":"https:\/\/europeanvalues.cz\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/#breadcrumb"},"inLanguage":"cs","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europeanvalues.cz\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/"]}]},{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/europeanvalues.cz\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/#primaryimage","url":"https:\/\/europeanvalues.cz\/wp-content\/uploads\/2023\/08\/Flag_of_Philippines.jpg","contentUrl":"https:\/\/europeanvalues.cz\/wp-content\/uploads\/2023\/08\/Flag_of_Philippines.jpg","width":2160,"height":1136},{"@type":"BreadcrumbList","@id":"https:\/\/europeanvalues.cz\/ec-president-von-der-leyen-visits-philippines-amid-weak-beijing-manila-ties\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dom\u016f","item":"https:\/\/europeanvalues.cz\/"},{"@type":"ListItem","position":2,"name":"EC President von der Leyen Visits Philippines Amid Weak Beijing-Manila Ties"}]},{"@type":"WebSite","@id":"https:\/\/europeanvalues.cz\/en\/#website","url":"https:\/\/europeanvalues.cz\/en\/","name":"European Values Center for Security Policy","description":"","publisher":{"@id":"https:\/\/europeanvalues.cz\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europeanvalues.cz\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cs"},{"@type":"Organization","@id":"https:\/\/europeanvalues.cz\/en\/#organization","name":"European Values Center for Security Policy","url":"https:\/\/europeanvalues.cz\/en\/","logo":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/europeanvalues.cz\/en\/#\/schema\/logo\/image\/","url":"https:\/\/europeanvalues.cz\/wp-content\/uploads\/2021\/04\/logo-horse.svg","contentUrl":"https:\/\/europeanvalues.cz\/wp-content\/uploads\/2021\/04\/logo-horse.svg","caption":"European Values Center for Security Policy"},"image":{"@id":"https:\/\/europeanvalues.cz\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/europeanvalues.cz\/en\/#\/schema\/person\/7724fb271acacd215231c937a200a510","name":"Ond\u0159ej Ber\u00e1nek","image":{"@type":"ImageObject","inLanguage":"cs","@id":"https:\/\/secure.gravatar.com\/avatar\/f89146eedd3ddff4c25476fbcda302860efe5ac77dc8e7ad9cd2b43a88c341ce?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f89146eedd3ddff4c25476fbcda302860efe5ac77dc8e7ad9cd2b43a88c341ce?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f89146eedd3ddff4c25476fbcda302860efe5ac77dc8e7ad9cd2b43a88c341ce?s=96&r=g","caption":"Ond\u0159ej Ber\u00e1nek"},"url":"https:\/\/europeanvalues.cz\/cs\/author\/ond-ber\/"}]}},"_links":{"self":[{"href":"https:\/\/europeanvalues.cz\/cs\/wp-json\/wp\/v2\/posts\/34394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europeanvalues.cz\/cs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/europeanvalues.cz\/cs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/europeanvalues.cz\/cs\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/europeanvalues.cz\/cs\/wp-json\/wp\/v2\/comments?post=34394"}],"version-history":[{"count":21,"href":"https:\/\/europeanvalues.cz\/cs\/wp-json\/wp\/v2\/posts\/34394\/revisions"}],"predecessor-version":[{"id":34436,"href":"https:\/\/europeanvalues.cz\/cs\/wp-json\/wp\/v2\/posts\/34394\/revisions\/34436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/europeanvalues.cz\/cs\/wp-json\/wp\/v2\/media\/34395"}],"wp:attachment":[{"href":"https:\/\/europeanvalues.cz\/cs\/wp-json\/wp\/v2\/media?parent=34394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/europeanvalues.cz\/cs\/wp-json\/wp\/v2\/categories?post=34394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/europeanvalues.cz\/cs\/wp-json\/wp\/v2\/tags?post=34394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}